{"id":1734,"date":"2025-11-03T16:19:25","date_gmt":"2025-11-03T16:19:25","guid":{"rendered":"https:\/\/afgassurancesmali.com\/fr\/?p=1734"},"modified":"2025-11-05T09:39:24","modified_gmt":"2025-11-05T09:39:24","slug":"assurance-maladie-groupe","status":"publish","type":"post","link":"https:\/\/afgassurancesmali.com\/fr\/assurance-maladie-groupe\/","title":{"rendered":"Assurance Maladie Groupe"},"content":{"rendered":"<p><strong>L\u2019harmonie entre performance, protection et innovation<\/strong><\/p>\n<p>Parce que la sant\u00e9 de vos collaborateurs est un pilier strat\u00e9gique de votre performance globale, nous vous proposons une solution d\u2019assurance sant\u00e9 groupe 100% digital \u00e0 la hauteur de vos engagements d\u2019employeur<\/p>\n<p>Ce contrat vous offre une couverture sant\u00e9 enti\u00e8rement digitalis\u00e9e permettant \u00e0 vos collaborateurs ainsi qu\u2019\u00e0 leur famille de b\u00e9n\u00e9ficier d\u2019un acc\u00e8s simplifi\u00e9 \u00e0 des soins de qualit\u00e9, d\u2019un remboursement des d\u00e9penses d\u2019ordre m\u00e9dical et chirurgical engag\u00e9s \u00e0 la suite de maladies, d\u2019accidents ou de maternit\u00e9s tout en all\u00e9geant les contraintes administratives \u00e0\u00a0l\u2019entreprise.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019harmonie entre performance, protection et innovation Parce que la sant\u00e9 de vos collaborateurs est un pilier strat\u00e9gique de votre performance globale, nous vous proposons une solution d\u2019assurance sant\u00e9 groupe 100% digital \u00e0 la hauteur de vos engagements d\u2019employeur Ce contrat vous offre une couverture sant\u00e9 enti\u00e8rement digitalis\u00e9e permettant \u00e0 vos collaborateurs ainsi qu\u2019\u00e0 leur famille [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,22],"tags":[],"class_list":["post-1734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produits-et-services","category-professionnels"],"acf":[],"views":251,"_links":{"self":[{"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/posts\/1734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/comments?post=1734"}],"version-history":[{"count":2,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/posts\/1734\/revisions"}],"predecessor-version":[{"id":1812,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/posts\/1734\/revisions\/1812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/media\/1751"}],"wp:attachment":[{"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/media?parent=1734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/categories?post=1734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afgassurancesmali.com\/fr\/wp-json\/wp\/v2\/tags?post=1734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}